{"id":37425,"date":"2024-12-10T10:46:38","date_gmt":"2024-12-10T14:46:38","guid":{"rendered":"https:\/\/payfacto.com\/?page_id=37425"},"modified":"2026-03-10T04:20:48","modified_gmt":"2026-03-10T08:20:48","slug":"azpos","status":"publish","type":"page","link":"https:\/\/payfacto.com\/fr\/azpos\/","title":{"rendered":"AzPOS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"37425\" class=\"elementor elementor-37425\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2ef2acb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ef2acb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e9a994\" data-id=\"1e9a994\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d7906b elementor-widget elementor-widget-heading\" data-id=\"6d7906b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Mises \u00e0 jour importantes pour les utilisateurs d'AzPOS<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d875f4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7d875f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60d9af4 elementor-widget elementor-widget-text-editor\" data-id=\"60d9af4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Restez inform\u00e9 des derniers changements r\u00e9glementaires affectant les activit\u00e9s de votre entreprise : cong\u00e9 de taxes temporaire, projet de loi 72 et migration\u00a0au MEV-WEB.<\/p><p>PayFacto est l\u00e0 pour vous accompagner dans ces mises \u00e0 jour essentielles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24b3ce7 elementor-widget elementor-widget-button\" data-id=\"24b3ce7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#azpos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b218c7e\" data-id=\"b218c7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-81bd179 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81bd179\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5432d7\" data-id=\"f5432d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-910ed36 elementor-widget elementor-widget-heading\" data-id=\"910ed36\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Adaptation aux nouvelles normes fiscales et r\u00e9glementaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9776e5e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9776e5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8568b5 elementor-widget-mobile__width-inherit elementor-hidden-mobile elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"b8568b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<strong style=\"color: #ff0202\">Attention :<\/strong> Le syst\u00e8me AzPOS n'est plus pris en charge et n'est pas compatible avec le MEV-WEB. Pour assurer la conformit\u00e9 de votre \u00e9tablissement aux nouvelles normes, il est imp\u00e9ratif de migrer vers <strong>Veloce<\/strong> ou <strong>Maitre'D<\/strong>.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00d2de0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"00d2de0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Cong\u00e9 de taxes temporaire<\/h3><p>Le gouvernement canadien a r\u00e9cemment annonc\u00e9 une mesure d&rsquo;all\u00e8gement temporaire de la taxe sur les produits et services (TPS) et de la taxe de vente harmonis\u00e9e (TVH) sur <a href=\"https:\/\/www.canada.ca\/fr\/ministere-finances\/nouvelles\/2024\/11\/plus-dargent-dans-vos-poches--un-conge-de-taxe-pour-tous-les-canadiens.html\" target=\"_blank\" rel=\"noopener\">certains produits essentiels<\/a>.<\/p><p><strong>Cette initiative sera en vigueur du 14 d\u00e9cembre 2024 au 15 f\u00e9vrier 2025.<\/strong><\/p><p>Les entreprises canadiennes sont donc tenues de mettre en \u0153uvre l&rsquo;\u00e9limination de la TPS\/TVH \u00e0 la caisse pour les produits admissibles <strong>\u00e0 compter du 14 d\u00e9cembre 2024<\/strong>.<\/p><p><b>Obtenez les instructions pour d\u00e9sactiver temporairement la TPS\/TVH sur votre Azpos en compl\u00e9tant le formulaire sur cette page.<\/b><\/p><h3 style=\"color: #000000;\"><span style=\"text-align: var(--bs-body-text-align);\">Projet de loi 72<\/span><\/h3><div><p>\u00c0 partir de la fin janvier 2025, les solutions de point de vente de PayFacto seront pleinement conformes au nouveau projet de loi 72.<\/p><p>Nos applications sont con\u00e7ues pour vous offrir la flexibilit\u00e9 n\u00e9cessaire afin de param\u00e9trer les pourboires selon vos pr\u00e9f\u00e9rences sur vos terminaux de paiement. Soyez assur\u00e9s que nous mettons tout en \u0153uvre pour faciliter cette transition et r\u00e9pondre \u00e0 vos besoins sp\u00e9cifiques.<\/p><\/div><p><b>Pour recevoir les instructions n\u00e9cessaires lorsqu&rsquo;elles seront pr\u00eates, veuillez SVP remplir le formulaire sur cette page.<\/b><\/p><h3>Migration au MEV-WEB<\/h3><p>Revenu Qu\u00e9bec a amorc\u00e9 une transition du Module d&rsquo;enregistrement des ventes (MEV) traditionnel vers le MEV-WEB, une solution infonuagique.<\/p><p><strong>Calendrier de mise en \u0153uvre :<\/strong><\/p><p>Les \u00e9tablissements de restauration en activit\u00e9 avant le 1\u1d49\u02b3 novembre 2023 doivent se conformer aux nouvelles mesures de facturation obligatoire d&rsquo;ici le 31 mai 2025. Toutefois, un d\u00e9lai suppl\u00e9mentaire de trois mois, jusqu&rsquo;au 31 ao\u00fbt 2025, peut \u00eatre accord\u00e9 si certaines conditions sont remplies, notamment la signature d&rsquo;un contrat avec un fournisseur avant le 1\u1d49\u02b3 juin 2025.<\/p><p><b>D\u00e9marrez votre processus de migration au MEV-WEB en remplissant le formulaire sur cette page.\u00a0<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec8ea3 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"1ec8ea3\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"azpos\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<iframe \n  id=\"JotFormIFrame-260415104528348\" \n  title=\"LP maitredpos.com\" \n  onload=\"window.parent.scrollTo(0,0)\" \n  allowtransparency=\"true\" \n  allow=\"geolocation; microphone; camera; fullscreen; payment\" \n  data-src=\"https:\/\/form.jotform.com\/260415104528348\/prefill\/6995db0d623763ad33386b77b610?language=fr-ca\" \n  frameborder=\"0\" \n  style=\"min-width:100%;max-width:100%;height:1100px;border:none;\" \n  scrolling=\"no\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\">\n<\/iframe> \n<script src=\"https:\/\/cdn.jotfor.ms\/s\/umd\/latest\/for-form-embed-handler.js\"><\/script> \n<script>\n  window.jotformEmbedHandler(\"iframe[id='JotFormIFrame-251395360646057']\", \"https:\/\/form.jotform.com\/\")\n<\/script>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7d674c1 elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d674c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31dd1ad\" data-id=\"31dd1ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1b6386 elementor-widget elementor-widget-heading\" data-id=\"c1b6386\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Adaptation aux nouvelles normes fiscales et r\u00e9glementaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9af23a5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9af23a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4a78b4 elementor-widget elementor-widget-text-editor\" data-id=\"e4a78b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #ff0202;\">Attention :<\/strong> Le syst\u00e8me AzPOS n&rsquo;est plus pris en charge et n&rsquo;est pas compatible avec le MEV-WEB. Pour assurer la conformit\u00e9 de votre \u00e9tablissement aux nouvelles normes, il est imp\u00e9ratif de migrer vers <strong>Veloce<\/strong> ou <strong>Maitre&rsquo;D<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48fda28 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"48fda28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Cong\u00e9 de taxes temporaire<\/h3><p>Le gouvernement canadien a r\u00e9cemment annonc\u00e9 une mesure d&rsquo;all\u00e8gement temporaire de la taxe sur les produits et services (TPS) et de la taxe de vente harmonis\u00e9e (TVH) sur <a href=\"https:\/\/www.canada.ca\/fr\/ministere-finances\/nouvelles\/2024\/11\/plus-dargent-dans-vos-poches--un-conge-de-taxe-pour-tous-les-canadiens.html\" target=\"_blank\" rel=\"noopener\">certains produits essentiels<\/a>.<\/p><p><strong>Cette initiative sera en vigueur du 14 d\u00e9cembre 2024 au 15 f\u00e9vrier 2025.<\/strong><\/p><p>Les entreprises canadiennes sont donc tenues de mettre en \u0153uvre l&rsquo;\u00e9limination de la TPS\/TVH \u00e0 la caisse pour les produits admissibles <strong>\u00e0 compter du 14 d\u00e9cembre 2024<\/strong>.<\/p><p><b>Obtenez les instructions pour d\u00e9sactiver temporairement la TPS\/TVH sur votre Azpos en compl\u00e9tant le formulaire sur cette page.<\/b><\/p><h3 style=\"color: #000000;\"><span style=\"text-align: var(--bs-body-text-align);\">Projet de loi 72<\/span><\/h3><div><p>\u00c0 partir de la fin janvier 2025, les solutions de point de vente de PayFacto seront pleinement conformes au nouveau projet de loi 72.<\/p><p>Nos applications sont con\u00e7ues pour vous offrir la flexibilit\u00e9 n\u00e9cessaire afin de param\u00e9trer les pourboires selon vos pr\u00e9f\u00e9rences sur vos terminaux de paiement. Soyez assur\u00e9s que nous mettons tout en \u0153uvre pour faciliter cette transition et r\u00e9pondre \u00e0 vos besoins sp\u00e9cifiques.<\/p><\/div><p><b>Pour recevoir les instructions n\u00e9cessaires lorsqu&rsquo;elles seront pr\u00eates, veuillez SVP remplir le formulaire sur cette page.<\/b><\/p><h3>Migration au MEV-WEB<\/h3><p>Revenu Qu\u00e9bec a amorc\u00e9 une transition du Module d&rsquo;enregistrement des ventes (MEV) traditionnel vers le MEV-WEB, une solution infonuagique.<\/p><p><strong>Calendrier de mise en \u0153uvre :<\/strong><\/p><p>Les \u00e9tablissements de restauration en activit\u00e9 avant le 1\u1d49\u02b3 novembre 2023 doivent se conformer aux nouvelles mesures de facturation obligatoire d&rsquo;ici le 31 mai 2025. Toutefois, un d\u00e9lai suppl\u00e9mentaire de trois mois, jusqu&rsquo;au 31 ao\u00fbt 2025, peut \u00eatre accord\u00e9 si certaines conditions sont remplies, notamment la signature d&rsquo;un contrat avec un fournisseur avant le 1\u1d49\u02b3 juin 2025.<\/p><p><b>D\u00e9marrez votre processus de migration au MEV-WEB en remplissant le formulaire sur cette page.\u00a0<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5fd8f0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e5fd8f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<iframe \n  id=\"JotFormIFrame-260415104528348\" \n  title=\"LP maitredpos.com\" \n  onload=\"window.parent.scrollTo(0,0)\" \n  allowtransparency=\"true\" \n  allow=\"geolocation; microphone; camera; fullscreen; payment\" \n  data-src=\"https:\/\/form.jotform.com\/260415104528348\/prefill\/6995db0d623763ad33386b77b610?language=fr-ca\" \n  frameborder=\"0\" \n  style=\"min-width:100%;max-width:100%;height:1100px;border:none;\" \n  scrolling=\"no\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\">\n<\/iframe> \n<script src=\"https:\/\/cdn.jotfor.ms\/s\/umd\/latest\/for-form-embed-handler.js\"><\/script> \n<script>\n  window.jotformEmbedHandler(\"iframe[id='JotFormIFrame-251395360646057']\", \"https:\/\/form.jotform.com\/\")\n<\/script>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-429bc07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"429bc07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be50c0d\" data-id=\"be50c0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8a3f04 elementor-widget elementor-widget-heading\" data-id=\"a8a3f04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Foire aux questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fa0190 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4fa0190\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0169bb7 elementor-widget elementor-widget-text-editor\" data-id=\"0169bb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Cong\u00e9 de taxes temporaire<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0fa2c1 elementor-widget elementor-widget-accordion\" data-id=\"e0fa2c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2351\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2351\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quels articles b\u00e9n\u00e9ficient de l'all\u00e9gement fiscal temporaire ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2351\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2351\"><ul><li><strong>Les v\u00eatements et chaussures pour enfants<\/strong> : V\u00eatements con\u00e7us pour les b\u00e9b\u00e9s et les enfants jusqu&rsquo;\u00e0 des tailles sp\u00e9cifiques.<\/li><li><strong>Couches pour enfants<\/strong> : Produits tels que les couches, les inserts, les doublures, les culottes d&rsquo;entra\u00eenement et les culottes en caoutchouc.<\/li><li><strong>Si\u00e8ges d&rsquo;auto pour enfants<\/strong> : Syst\u00e8mes de retenue ou si\u00e8ges d&rsquo;appoint r\u00e9pondant aux normes de s\u00e9curit\u00e9 canadiennes.<\/li><li><strong>Jouets pour enfants<\/strong> : Articles tels que les jeux de soci\u00e9t\u00e9, les poup\u00e9es, les peluches et les jeux de construction destin\u00e9s aux enfants de moins de 14 ans.<\/li><li><strong>Puzzles<\/strong> : Puzzles adapt\u00e9s \u00e0 tous les \u00e2ges.<\/li><li><strong>Consoles de jeux vid\u00e9o et accessoires<\/strong> : Consoles, contr\u00f4leurs et supports de jeu physiques.<\/li><li><strong>Livres et journaux imprim\u00e9s<\/strong> : Livres et journaux physiques contenant des nouvelles et des \u00e9ditoriaux.<\/li><li><strong>Arbres de No\u00ebl<\/strong> : Arbres naturels et artificiels.<\/li><li><strong>Aliments et boissons<\/strong> : Articles destin\u00e9s \u00e0 la consommation humaine, y compris certaines boissons alcoolis\u00e9es contenant moins de 7 % d&rsquo;alcool par volume.<\/li><\/ul><p><a href=\"https:\/\/www.canada.ca\/fr\/ministere-finances\/nouvelles\/2024\/11\/plus-dargent-dans-vos-poches--un-conge-de-taxe-pour-tous-les-canadiens.html\" target=\"_blank\" rel=\"noopener\">La liste d\u00e9taill\u00e9e est disponible ici.<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2352\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2352\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment cette mesure affecte-t-elle les entreprises ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2352\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2352\"><p>Les entreprises qui vendent des produits admissibles doivent adapter leurs syst\u00e8mes de point de vente afin de supprimer les frais de TPS\/TVH sur les produits admissibles au cours de la p\u00e9riode d&rsquo;all\u00e9gement. Cela n\u00e9cessite la mise \u00e0 jour des param\u00e8tres fiscaux afin de garantir la conformit\u00e9 et l&rsquo;exactitude des prix pour les consommateurs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2353\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2353\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Les entreprises peuvent-elles mettre \u00e0 jour leurs param\u00e8tres fiscaux avant le d\u00e9but de la p\u00e9riode d'all\u00e8gement ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2353\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2353\"><p>Non, les entreprises doivent continuer \u00e0 percevoir les taxes applicables jusqu&rsquo;au d\u00e9but de la p\u00e9riode d&rsquo;all\u00e8gement, le 14 d\u00e9cembre 2024.<\/p><p>Toutefois, il est conseill\u00e9 de se pr\u00e9parer \u00e0 l&rsquo;avance pour mettre en \u0153uvre rapidement les changements d\u00e8s le d\u00e9but de la p\u00e9riode et les annuler apr\u00e8s sa fin, le 15 f\u00e9vrier 2025, afin d&rsquo;\u00e9viter les erreurs.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2354\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-2354\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Que se passe-t-il si un article admissible est pay\u00e9 avant la p\u00e9riode d'all\u00e9gement mais livr\u00e9 pendant cette p\u00e9riode ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2354\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-2354\"><p>Pour que l&rsquo;all\u00e9gement fiscal s&rsquo;applique, le paiement et la livraison de l&rsquo;article admissible doivent tous deux <a href=\"https:\/\/www.canada.ca\/fr\/services\/impots\/prestations-pour-enfants-et-familles\/conge-tps-tvh-fetes.html\" target=\"_blank\" rel=\"noopener\">avoir lieu au cours de la p\u00e9riode d&rsquo;all\u00e9gement<\/a>. Si un acompte a \u00e9t\u00e9 vers\u00e9 avant le 14 d\u00e9cembre 2024, l&rsquo;article n&rsquo;est \u00e9ligible que si le montant restant est pay\u00e9 et que l&rsquo;article est livr\u00e9 entre le 14 d\u00e9cembre 2024 et le 15 f\u00e9vrier 2025.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2355\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-2355\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Est-ce que les achats en ligne b\u00e9n\u00e9ficient de l'all\u00e9gement fiscal ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2355\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-2355\"><p>Oui, les achats en ligne de biens \u00e9ligibles sont \u00e9ligibles, \u00e0 condition que les articles soient pay\u00e9s en totalit\u00e9 et livr\u00e9s au cours de la p\u00e9riode d&rsquo;all\u00e9gement. Le moment de la livraison est crucial pour d\u00e9terminer l&rsquo;\u00e9ligibilit\u00e9.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2356\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-2356\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Cet all\u00e9gement fiscal est-il disponible dans toutes les provinces ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2356\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-2356\"><p>L&rsquo;all\u00e8gement de la TPS s&rsquo;applique \u00e0 l&rsquo;ensemble du pays. Dans les provinces o\u00f9 la TVH est applicable (Ontario, Terre-Neuve-et-Labrador, Nouvelle-\u00c9cosse, Nouveau-Brunswick et l&rsquo;\u00cele-du-Prince-\u00c9douard), l&rsquo;all\u00e8gement s&rsquo;applique \u00e0 la fois \u00e0 la partie f\u00e9d\u00e9rale et \u00e0 la partie provinciale de la taxe.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2357\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-2357\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Que doivent faire les entreprises pour se pr\u00e9parer ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2357\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-2357\"><p>Les entreprises doivent revoir leurs offres de produits, mettre \u00e0 jour leurs syst\u00e8mes de point de vente et former leur personnel afin de garantir la conformit\u00e9 pendant la p\u00e9riode d&rsquo;all\u00e8gement.<\/p><p>Pour de plus amples informations, veuillez consulter <a href=\"https:\/\/www.canada.ca\/fr\/ministere-finances\/nouvelles\/2024\/11\/plus-dargent-dans-vos-poches--un-conge-de-taxe-pour-tous-les-canadiens.html\" target=\"_blank\" rel=\"noopener\">l&rsquo;annonce officielle du minist\u00e8re des Finances du Canada<\/a>.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dd8de3 elementor-widget elementor-widget-text-editor\" data-id=\"3dd8de3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Projet de loi 72<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5633994 elementor-widget elementor-widget-accordion\" data-id=\"5633994\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9031\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9031\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qu'est-ce que le projet de loi 72 et comment affecte-t-il les restaurateurs et les bars ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9031\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9031\"><p>Le projet de loi 72, adopt\u00e9 le 7 novembre 2024, vise \u00e0 prot\u00e9ger les consommateurs contre les pratiques commerciales abusives et \u00e0 offrir une meilleure transparence en mati\u00e8re de prix et de cr\u00e9dit. Pour les restaurateurs et les bars, cela implique des changements dans la mani\u00e8re dont les pourboires sont sugg\u00e9r\u00e9s et calcul\u00e9s, ainsi que des obligations accrues en mati\u00e8re d&rsquo;affichage des prix.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9032\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-9032\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment les suggestions de pourboire doivent-elles \u00eatre pr\u00e9sent\u00e9es selon la nouvelle loi ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9032\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-9032\"><p>Les suggestions de pourboire sur les terminaux de paiement doivent d\u00e9sormais \u00eatre calcul\u00e9es sur le montant avant taxes. De plus, les options de pourboire doivent \u00eatre pr\u00e9sent\u00e9es de mani\u00e8re neutre et uniforme, sans mettre en avant un pourcentage sp\u00e9cifique, permettant ainsi au consommateur de choisir librement le montant qu&rsquo;il souhaite laisser.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9033\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-9033\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quand ces nouvelles dispositions sur les pourboires entreront-elles en vigueur ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9033\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-9033\"><p>Les dispositions concernant le calcul et la pr\u00e9sentation des pourboires entreront en vigueur six mois apr\u00e8s la sanction de la loi, soit le 7 mai 2025, afin de permettre aux \u00e9tablissements de s&rsquo;adapter \u00e0 ces nouvelles exigences.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9034\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-9034\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">O\u00f9 puis-je obtenir plus d'informations sur le projet de loi 72 ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-9034\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-9034\"><p>Pour plus de d\u00e9tails, vous pouvez consulter <a href=\"https:\/\/www.assnat.qc.ca\/fr\/travaux-parlementaires\/projets-loi\/projet-loi-72-43-1.html\" target=\"_blank\" rel=\"noopener\">le site de l&rsquo;Assembl\u00e9e nationale du Qu\u00e9bec<\/a> ou <a href=\"https:\/\/www.quebec.ca\/nouvelles\/actualites\/details\/depot-du-projet-de-loi-no-72-pour-proteger-le-portefeuille-et-le-pouvoir-dachat-des-familles-quebecoises-58192\" target=\"_blank\" rel=\"noopener\">le communiqu\u00e9 officiel du gouvernement du Qu\u00e9bec<\/a>.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0318109 elementor-widget elementor-widget-text-editor\" data-id=\"0318109\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>MEV-WEB<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d035d5 elementor-widget elementor-widget-accordion\" data-id=\"8d035d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1471\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1471\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment obtenir le nouveau code MEV compatible avec le MEV-WEB via ClicS\u00c9QUR ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1471\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1471\"><p class=\"\" data-pm-slice=\"0 0 []\">Pour obtenir le code MEV pour le MEV-WEB via ClicS\u00c9QUR, contactez les services de ClicS\u00c9QUR par t\u00e9l\u00e9phone :<\/p><p class=\"\"><strong>Qu\u00e9bec :<\/strong> 418 652-6014,<\/p><p class=\"\"><strong>Montr\u00e9al :<\/strong> 514 287-2014,<\/p><p class=\"\"><strong>Ailleurs (Canada) :<\/strong> 1 855 271-0519.<\/p><p class=\"\">Alternativement, remplissez les formulaires FO-350.CA <a href=\"https:\/\/www.revenuquebec.ca\/documents\/fr\/formulaires\/fo\/FO-350.CA%282023-11%29DXI.pdf\" target=\"_blank\" rel=\"noopener\">Voir le formulaire<\/a> (pour les commer\u00e7ants actuels) ou FO-350.DE <a href=\"https:\/\/www.revenuquebec.ca\/documents\/fr\/formulaires\/fo\/FO-350.DE%282023-11%29.pdf\" target=\"_blank\" rel=\"noopener\">Voir le formulaire ici<\/a> (pour les nouvelles entreprises soumises \u00e0 la r\u00e9glementation de la facture obligatoire) pour recevoir le code.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1472\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1472\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quels sont les mat\u00e9riels pr\u00e9requis pour int\u00e9grer le MEV-WEB ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1472\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1472\"><p class=\"\" data-rte-preserve-empty=\"true\" data-pm-slice=\"1 1 []\">De l&rsquo;\u00e9quipement r\u00e9pondant au minimum requis par notre SEV certifi\u00e9 en termes de m\u00e9moire, de puissance de CPU et une version de Microsoft Windows r\u00e9cente. Contactez-nous pour en savoir plus.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1473\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1473\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment le MEV-WEB interagit-il avec mon syst\u00e8me POS existant ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1473\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1473\"><p class=\"\" data-rte-preserve-empty=\"true\" data-pm-slice=\"1 1 []\">Le MEV-WEB requiert une version certifi\u00e9e de votre logiciel POS pour communiquer efficacement avec la plateforme, recueillant les donn\u00e9es de transaction et les transmettant \u00e0 Revenu Qu\u00e9bec. Le MEV-WEB demande une connexion Internet.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1474\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1474\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Dois-je informer Revenu Qu\u00e9bec une fois que la transition vers le MEV-WEB est compl\u00e8te ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1474\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1474\"><p class=\"\" data-rte-preserve-empty=\"true\" data-pm-slice=\"1 1 []\">Le MEV-WEB transmettra automatiquement les donn\u00e9es de transaction \u00e0 Revenu Qu\u00e9bec, mais v\u00e9rifiez avec Revenu Qu\u00e9bec si une notification suppl\u00e9mentaire est n\u00e9cessaire.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e13bd69 elementor-widget elementor-widget-text-editor\" data-id=\"e13bd69\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consultez <a href=\"https:\/\/mevweb.ca\/questions-frequentes\" target=\"_blank\" rel=\"noopener\">https:\/\/mevweb.ca\/questions-frequentes<\/a> pour obtenir des r\u00e9ponses \u00e0 toutes vos questions relatives au MEV-WEB.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0817d7c elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0817d7c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6ca6179\" data-id=\"6ca6179\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1ed972 elementor-widget elementor-widget-heading\" data-id=\"f1ed972\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Besoin d'aide ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff9152c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ff9152c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ef12ac elementor-widget elementor-widget-text-editor\" data-id=\"6ef12ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Contactez nous ! Notre \u00e9quipe d&rsquo;assistance d\u00e9vou\u00e9e est \u00e0 port\u00e9e de main.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ecaccaf\" data-id=\"ecaccaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9a94ca3\" data-id=\"9a94ca3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mises \u00e0 jour importantes pour les utilisateurs d&rsquo;AzPOS Restez inform\u00e9 des derniers changements r\u00e9glementaires affectant les activit\u00e9s de votre entreprise : cong\u00e9 de taxes temporaire, projet de loi 72 et migration\u00a0au MEV-WEB. PayFacto est l\u00e0 pour vous accompagner dans ces mises \u00e0 jour essentielles. Contactez-nous Adaptation aux nouvelles normes fiscales et r\u00e9glementaires Attention : Le syst\u00e8me AzPOS n&rsquo;est plus pris en charge et n&rsquo;est pas compatible avec le MEV-WEB. Pour assurer la conformit\u00e9 de votre \u00e9tablissement aux nouvelles normes, il est imp\u00e9ratif de migrer vers Veloce ou Maitre&rsquo;D. Cong\u00e9 de taxes temporaire Le gouvernement canadien a r\u00e9cemment annonc\u00e9 une mesure<\/p>\n","protected":false},"author":23,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-37425","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/pages\/37425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/comments?post=37425"}],"version-history":[{"count":0,"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/pages\/37425\/revisions"}],"wp:attachment":[{"href":"https:\/\/payfacto.com\/fr\/wp-json\/wp\/v2\/media?parent=37425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}